{"id":72,"date":"2013-11-21T12:33:32","date_gmt":"2013-11-21T12:33:32","guid":{"rendered":"http:\/\/trachtenverein-waldburg.eu\/starker-nachwuchs-sichert-die-zukunft-des-vereins-2"},"modified":"2013-11-21T12:33:32","modified_gmt":"2013-11-21T12:33:32","slug":"starker-nachwuchs-sichert-die-zukunft-des-vereins-2","status":"publish","type":"post","link":"https:\/\/www.trachtenverein-waldburg.de\/en\/starker-nachwuchs-sichert-die-zukunft-des-vereins-2","title":{"rendered":"Starker Nachwuchs sichert die Zukunft des Vereins"},"content":{"rendered":"<p> \tUnter diese \u00dcberschrift haben wir schon im Jahr 2012 unsere R\u00fcckschau auf die Jugendarbeit des Vereins gestellt, und k\u00f6nnen heute mit grosser Freude und Genugtuung feststellen, dass diese Aussage f\u00fcr uns noch immer aktuell und zutreffend ist, denn auch 2013 war das Aktionsprogramm der Jugendgruppe angef\u00fcllt mit interessanten Auftritten und erlebnisreichen Freizeitmassnahmen. Besonders beliebt ist das Gestalten von Unterhaltungsnachmittagen in sozialen Einrichtungen der n\u00e4heren Region, in Baienfurt, Bodnegg, und Vogt, sowie das Mitwirken am Heimatabend und Seniorennachmittag in Waldburg.<\/p>\n<p>  <!--more-->  <\/p>\n<p> \tEinerseits ist dabei der Anfahrtsweg mit relativ geringem Aufwand zu bew\u00e4ltigen, und andererseits k\u00f6nnen die Burschen und Dirndl dabei einem sehr dankbaren Publikum mit Freude und Eifer zeigen, was sie in ca. 30 Probenachmittagen an Plattler-, Volks- und Jugendt\u00e4nzen sehr erfolgreich ge\u00fcbt haben. Dar\u00fcber hinaus wurden auch interessante Fahrten unternommen, bei denen oft das Freizeiterleben mit wirkungsvollen Programmauftritten verbunden wird. Als besonderer H\u00f6hepunkt kann in diesem Zusammenhang das Mitwirken an der \u201eEuropeade der Folklore\u201c in Gotha in Th\u00fcringen herausgestellt werden. Dieses gr\u00f6sste Fest Europas im Bereich von Folklore und Brauchtum feierte sein 50. Jubil\u00e4um in einer sch\u00f6nen Stadt in Deutschland und war deshalb auch Anlass f\u00fcr die Jugend des Bodenseegauverbandes erstmalig daran teilzunehmen. Dieses Bestreben wurde auch von unserem Verein unterst\u00fctzt und ein gemeinsamer grosser Bus \u00fcber die Fa. Grabherr daf\u00fcr organisiert. Die Mehrzahl der teilnehmenden Jugendlichen der Gaujugend waren junge Burschen und Dirndl unseres Vereins, und f\u00fcr diese ein nachhaltig wirkendes Erlebnis. Ein weiteres grosses Ereigniss war im M\u00e4rz der Besuch des Landtages in Stuttgart, verbunden mit F\u00fchrung und Zusammentreffen mit Landtagsabgeordneten, des Landtagspr\u00e4sidenten und Erleben einer Landtagsdebatte. Diese Veranstaltung wurde von der TJBW, der Jugendorganisation des Landesvorstandes organisiert und von unserer Jugendgruppe gern angenommen. Ausserdem wirkte unsere Jugend mit beim Deutschen Kinder- und Trachtentag im M\u00e4rz in Bensheim, am Gaufest des Bodensee- und des S\u00fcdwestgaus im Mai in Schorndorf, am Gauheimatabend im Juni in Wangen zum 100. Jubil\u00e4um des Wangener Trachtenvereins und weiteren Veranstaltungen der Gaujugend. Auch die Freizeitgestaltung kam nicht zu kurz, mit so interessanten Aktivit\u00e4ten, wie das Jugendzeltlager im Juni in Rot an der Rot oder das Sommerferienprogramm im August mit Kinoabend im Vereinsheim und ein Besuch auf der Waldburg mit Grillen in der Burgschenke und Erscheinen des Burggespenstes. Ausserdem liegt die Weihnachtsfeier noch vor uns, auf die sich die Burschen und Dirndl wieder mit einem Theaterspiel und grossem Eifer vorbereiten.<br \/> \tAuch die Ausbildung und Anleitung des Jugendleiterteams ist wichtiger Bestandteil der Jugendarbeit. Sie wird im Wesentlichen vom Bodenseegauverband organisiert und schliesst mit der \u00dcbergabe der Jugendleiterkarte durch den TJBW ab, die eine Zertifizierung von kompetenter Arbeit und F\u00fchrung von Jugendlichen bedeutet. Besonders erw\u00e4hnen m\u00f6chten wir das Jugendleiterseminar im November in Waldburg mit dem Thema \u201eErste Hilfe\u201c und von Josef Sonntag von der Ortsgruppe Waldburg sehr interessant und engagiert gestaltet wurde.<br \/> \tZum Schluss unseres Berichtes k\u00f6nnen wir auch die Dankesworte vom R\u00fcckblick 2012 w\u00f6rtlich wiederholen, denn sie sind noch genau so zutreffend und ehrlich gemeint. Wir sind nach wie vor der \u00dcberzeugung, dass mit dieser erfolgreichen R\u00fcckschau der Trachtenverein Waldburg dem n\u00e4chsten! und den n\u00e4chsten! Jahren optimistisch entgegenblicken kann und m\u00f6chte sich ganz herzlich bei allen Burschen und Dirndln der Jugendgruppe f\u00fcr ihr fleissiges \u201eMittendrin- und Dabeisein\u201c&nbsp; bedanken. Ein herzlicher Dank gilt auch dem Jugendleiterteam Albert, Dieter, Petra und Christiane und ganz besonders den Eltern der Jugendlichen, ohne deren breite Unterst\u00fctzung durch Fahrdienste zu Proben, Auftritten und Festen, durch Kuchenspenden, aktive Mitarbeit bei Veranstaltungen und und \u2026 diese gute Nachwuchsarbeit nicht denkbar w\u00e4re. Neben organisatorischen und handwerklichen Hilfsleistungen sind zur Bew\u00e4ltigung dieser Aufgaben auch immer finanzielle Aufwendungen erforderlich. Vorstand und Leitungsausschuss des Trachtenvereins werden sich weiterhin bem\u00fchen, diese m\u00f6glichst aus der Vereinskasse zu bestreiten und die Beteiligungen der Eltern so gering wie m\u00f6glich zu halten. Daf\u00fcr bitten wir um Verst\u00e4ndnis und m\u00f6chten nochmals ein herzliches Vergelt\u2019s Gott! sagen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter diese \u00dcberschrift haben wir schon im Jahr 2012 unsere R\u00fcckschau auf die Jugendarbeit des Vereins gestellt, und k\u00f6nnen heute mit grosser Freude und Genugtuung feststellen, dass diese Aussage f\u00fcr &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.trachtenverein-waldburg.de\/en\/starker-nachwuchs-sichert-die-zukunft-des-vereins-2\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Starker Nachwuchs sichert die Zukunft des Vereins&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-72","post","type-post","status-publish","format-standard","hentry","category-aktuelles"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/posts\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":0,"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/posts\/72\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/categories?post=72"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.trachtenverein-waldburg.de\/en\/wp-json\/wp\/v2\/tags?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}